{"id":17381,"date":"2023-03-22T13:57:50","date_gmt":"2023-03-22T13:57:50","guid":{"rendered":"https:\/\/sianjilife.com\/sianji-villa-residence\/"},"modified":"2023-03-24T23:55:39","modified_gmt":"2023-03-24T23:55:39","slug":"sianji-villa-residence","status":"publish","type":"page","link":"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/","title":{"rendered":"Sianji Villa &amp; Residence"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"17381\" class=\"elementor elementor-17381 elementor-17379\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d433fb4 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3d433fb4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-535f6e3e\" data-id=\"535f6e3e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b431085 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b431085\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b99a3fb\" data-id=\"b99a3fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f571d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"0f571d0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aeb6592\" data-id=\"aeb6592\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68cb670 wpr-logo-position-center elementor-widget elementor-widget-wpr-logo\" data-id=\"68cb670\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-logo.default\">\n\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"wpr-logo elementor-clearfix\">\n\n\t\t\t\t\t\t\t\t<picture class=\"wpr-logo-image\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/Sianji-Villa-Residence-Logo-1.png?w=640&#038;ssl=1\" alt=\"\">\n\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"wpr-logo-url\" rel=\"home\" aria-label=\"\" href=\"https:\/\/sianjilife.com\/en\/\"><\/a>\n\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a class=\"wpr-logo-url\" rel=\"home\" aria-label=\"\" href=\"https:\/\/sianjilife.com\/en\/\"><\/a>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e92f892 elementor-invisible elementor-widget elementor-widget-video\" data-id=\"e92f892\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/GJxSLmO4ds0&quot;,&quot;start&quot;:5,&quot;end&quot;:5,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;yt_privacy&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24d2a3d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"24d2a3d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6145448\" data-id=\"6145448\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea97da6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"ea97da6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77b4a7b\" data-id=\"77b4a7b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20354b7 elementor-widget elementor-widget-heading\" data-id=\"20354b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A privileged life embracing the deep blue sea of Bodrum!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8dd98b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8dd98b9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c4da60\" data-id=\"1c4da60\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0c5114 elementor-widget elementor-widget-text-editor\" data-id=\"c0c5114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 3\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>While the world is changing rapidly, we offer you a life where you feel peaceful with the future assurance of the value your investment gains, with the relaxing and refreshing hospitality of Sianji Hotel for a lifetime.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d92c016 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"d92c016\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-579f568\" data-id=\"579f568\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4736d80 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"4736d80\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99cb61a\" data-id=\"99cb61a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43fbd4ab elementor-widget elementor-widget-heading\" data-id=\"43fbd4ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5 STAR COMFORT SERVICES<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0a09aa3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"0a09aa3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-3e0c867\" data-id=\"3e0c867\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa29393 elementor-widget elementor-widget-pix-card\" data-id=\"aa29393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/guvenlik.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/guvenlik.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/guvenlik.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/guvenlik.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-5dd4b30\" data-id=\"5dd4b30\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd41f40 elementor-widget elementor-widget-pix-card\" data-id=\"cd41f40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/karsilama-1-1.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/karsilama-1-1.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/karsilama-1-1.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/karsilama-1-1.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-2ccfc95\" data-id=\"2ccfc95\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5953c8e elementor-widget elementor-widget-pix-card\" data-id=\"5953c8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/belboy-hizmeti.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/belboy-hizmeti.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/belboy-hizmeti.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/belboy-hizmeti.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-64ca7aa\" data-id=\"64ca7aa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb8ced0 elementor-widget elementor-widget-pix-card\" data-id=\"cb8ced0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/resepsiyon-hizmeti.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/resepsiyon-hizmeti.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/resepsiyon-hizmeti.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/resepsiyon-hizmeti.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-fd2d922\" data-id=\"fd2d922\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c1c5b6 elementor-widget elementor-widget-pix-card\" data-id=\"3c1c5b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/house-keeping-hizmeti.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/house-keeping-hizmeti.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/house-keeping-hizmeti.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/house-keeping-hizmeti.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-4eddb4d\" data-id=\"4eddb4d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8f311f elementor-widget elementor-widget-pix-card\" data-id=\"c8f311f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/teknik.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/teknik.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/teknik.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/teknik.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb4f42a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"fb4f42a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-11332ab\" data-id=\"11332ab\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ab964c elementor-widget elementor-widget-pix-card\" data-id=\"8ab964c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/bahce-bakimi.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/bahce-bakimi.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/bahce-bakimi.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/bahce-bakimi.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-2dd2816\" data-id=\"2dd2816\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40cc99c elementor-widget elementor-widget-pix-card\" data-id=\"40cc99c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sport-centre.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service \" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sport-centre.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sport-centre.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sport-centre.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service <\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-e0519f1\" data-id=\"e0519f1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-100dd36 elementor-widget elementor-widget-pix-card\" data-id=\"100dd36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/plaj-kullanimi.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/plaj-kullanimi.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/plaj-kullanimi.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/plaj-kullanimi.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-a87eaeb\" data-id=\"a87eaeb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ebadb8 elementor-widget elementor-widget-pix-card\" data-id=\"7ebadb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/havuz-kullanimi.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/havuz-kullanimi.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/havuz-kullanimi.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/havuz-kullanimi.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-decc29d\" data-id=\"decc29d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b01861 elementor-widget elementor-widget-pix-card\" data-id=\"5b01861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/hamam-sauna.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/hamam-sauna.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/hamam-sauna.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/hamam-sauna.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-bb1a117\" data-id=\"bb1a117\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ece87b elementor-widget elementor-widget-pix-card\" data-id=\"8ece87b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a   href=\"\" class=\" fly\"><div class=\"card    rounded-0  overflow-hidden \" ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" width=\"900\" height=\"1200\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/kuafor-pic.jpg?fit=900%2C1200&amp;ssl=1\" class=\"w-100\" alt=\"Valet Service\" srcset=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/kuafor-pic.jpg?w=900&amp;ssl=1 900w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/kuafor-pic.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/kuafor-pic.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><div class=\"pix-card-content bg-white\"><div class=\"card-body\"><div class=\"d-flex justify-content-between align-items-center font-weight-bold text-heading-default h6 heading-font\"><div style=\"\" class=\"card-title mb-0 font-weight-bold text-heading-default h6 heading-font\">Valet Service<\/div><div style=\"\" class=\"font-weight-bold text-heading-default\"><svg class=\"pixfort-icon \" width=\"24\" height=\"24\"  data-name=\"Line\/pixfort-icon-arrow-right-2\" viewBox=\"2 2 20 20\"><polyline fill=\"none\" stroke=\"var(--pf-icon-color)\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"var(--pf-icon-stroke-width)\" points=\"9.5 17 14.5 12 9.5 7\"\/><\/svg><\/div><\/div><\/div><\/div><\/div><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56e5e87 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"56e5e87\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-625d225\" data-id=\"625d225\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e94a058 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2e94a058\" data-element_type=\"section\" data-e-type=\"section\" id=\"pix_section_boxes\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-90dced4\" data-id=\"90dced4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6628920 elementor-widget elementor-widget-heading\" data-id=\"6628920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PENTHOUSE 3+1 \/ 7+1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bec4e89 elementor-widget elementor-widget-text-editor\" data-id=\"bec4e89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Enjoy the magnificent view of the islands in the nature embracing the deep blue sea of Bodrum.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-118f3b87 animated-slow elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"118f3b87\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"katman_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 27.1 30.8\" style=\"enable-background:new 0 0 27.1 30.8;\" xml:space=\"preserve\"><path d=\"M7.3,14.9v-2.3h2.3v2.3H7.3z M17.3,14.9v-2.3h2.3v2.3H17.3z M0.2,30.5v-11h1.7v-7.4c0-1.6,0.3-3.1,0.9-4.5S4.2,5,5.3,3.9 C6.3,2.9,7.6,2,9,1.4c1.4-0.6,2.9-0.9,4.5-0.9s3.1,0.3,4.5,0.9c1.4,0.6,2.7,1.4,3.7,2.5c1.1,1.1,1.9,2.3,2.5,3.7s0.9,2.9,0.9,4.5 v7.4h1.7v11H0.2z M1.6,29.1h4.5V21H1.6V29.1z M7.5,29.1h5.3V21H7.5V29.1z M3.3,19.6h9.5V2c-2.5,0.1-4.7,1.1-6.6,3 c-1.9,1.9-2.9,4.3-2.9,7.2V19.6z M14.2,19.6h9.5v-7.4c0-2.9-1-5.3-2.9-7.2c-1.9-1.9-4.2-2.9-6.6-3V19.6z M14.2,29.1h5.3V21h-5.3 V29.1z M21,29.1h4.5V21H21V29.1z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBalcony\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-516035f animated-slow elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"516035f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"katman_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 30.2 22.5\" style=\"enable-background:new 0 0 30.2 22.5;\" xml:space=\"preserve\"><path d=\"M6,16c1.5-0.1,3-0.3,4.5-0.4c1.5-0.1,3-0.1,4.6-0.1s3,0,4.6,0.1c1.5,0.1,3,0.2,4.5,0.4l-5.7-7l-4.6,5.6l-3.4-4.2L6,16z  M1.7,22.4c-0.4,0.1-0.8,0.1-1.1-0.2s-0.5-0.6-0.5-1.1V1.3c0-0.5,0.2-0.9,0.5-1.1C0.9,0.1,1.3,0,1.7,0.1c0.6,0.1,1.3,0.3,2.1,0.5 c0.9,0.2,1.9,0.4,3,0.6c1.1,0.2,2.4,0.4,3.7,0.5C11.9,2,13.5,2,15.1,2s3.1-0.1,4.5-0.2c1.4-0.2,2.6-0.3,3.8-0.5 c1.1-0.2,2.1-0.4,2.9-0.6c0.8-0.2,1.5-0.4,2.1-0.5c0.4-0.1,0.8-0.1,1.1,0.1c0.3,0.2,0.5,0.6,0.5,1.1v19.8c0,0.5-0.2,0.9-0.5,1.1 c-0.3,0.2-0.7,0.3-1.1,0.2c-0.6-0.2-1.3-0.4-2.1-0.6c-0.8-0.2-1.8-0.4-2.9-0.7c-1.1-0.2-2.4-0.4-3.8-0.5c-1.4-0.2-2.9-0.2-4.5-0.2 s-3.2,0.1-4.5,0.2c-1.4,0.2-2.6,0.3-3.7,0.5c-1.1,0.2-2.1,0.4-3,0.7C2.9,22,2.2,22.2,1.7,22.4z M1.5,21c2.2-0.7,4.4-1.2,6.7-1.5 s4.6-0.5,6.9-0.5s4.6,0.2,6.9,0.5s4.5,0.8,6.7,1.5V1.5C26.5,2.2,24.3,2.7,22,3c-2.3,0.3-4.6,0.5-6.9,0.5S10.5,3.3,8.2,3 C5.9,2.7,3.7,2.2,1.5,1.5V21z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSea View\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22e8ee6 animated-slow elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"22e8ee6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"katman_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 39.6 38.9\" style=\"enable-background:new 0 0 39.6 38.9;\" xml:space=\"preserve\"><path d=\"M19.7,38.3c-2.7,0-5.2-0.5-7.5-1.5s-4.3-2.3-6.1-4c-1.7-1.7-3.1-3.7-4-6s-1.4-4.8-1.4-7.5c0-2.6,0.5-5.1,1.4-7.4 s2.3-4.3,4-6.1s3.7-3.1,6.1-4.1c2.3-1,4.8-1.5,7.5-1.5c2.4,0,4.6,0.4,6.6,1.1s3.9,1.8,5.6,3.1l-1.6,1.6c-1.5-1.2-3.1-2.1-4.9-2.7 s-3.7-0.9-5.7-0.9C15,2.5,11,4.1,7.8,7.3s-4.8,7.2-4.8,11.9S4.5,28,7.8,31.2S15,36,19.7,36s8.7-1.6,11.9-4.8s4.8-7.2,4.8-11.9 c0-1-0.1-2-0.2-2.9c-0.2-0.9-0.4-1.8-0.7-2.7l1.8-1.8c0.5,1.1,0.8,2.3,1.1,3.5s0.4,2.5,0.4,3.8c0,2.7-0.5,5.2-1.5,7.5 s-2.3,4.3-4,6.1c-1.7,1.7-3.7,3.1-6,4S22.4,38.3,19.7,38.3z M16.7,27.7l-7.6-7.6l1.7-1.8l5.9,5.9L37,4l1.8,1.7L16.7,27.7z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBalcony\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3d98cc elementor-widget__width-auto elementor-widget elementor-widget-pix-button\" data-id=\"b3d98cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  href=\"https:\/\/sianjilife.com\/wp-content\/uploads\/2023\/03\/Varlik-1-1.png\" class=\"btn m-0      btn-brown d-inline-flex align-items-center      btn-sm\" target=\"_blank\" rel=\"noopener\"    ><span class=\"font-weight-bold \" >360 Tour<\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35e8f69 elementor-widget__width-auto elementor-widget elementor-widget-pix-button\" data-id=\"35e8f69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  href=\"https:\/\/l24.im\/arH8c\" class=\"btn m-0      btn-brown d-inline-flex align-items-center      btn-sm\" target=\"_blank\" rel=\"noopener\"    ><span class=\"font-weight-bold \" >Room Video<\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa2bf34 elementor-widget__width-auto elementor-widget elementor-widget-pix-button\" data-id=\"aa2bf34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  href=\"https:\/\/l24.im\/RBIEQr\" class=\"btn m-0      btn-brown d-inline-flex align-items-center      btn-sm\" target=\"_blank\" rel=\"noopener\"    ><span class=\"font-weight-bold \" >360 Tour<\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-36a78506\" data-id=\"36a78506\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af207b3 elementor-widget__width-inherit elementor-widget elementor-widget-pix-img-slider\" data-id=\"af207b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-img-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pixfort-swiper position-relative   \"><div class=\"position-relative\"><div class=\"swiper  pix-style-standard pix-effect-standard \" data-swiper='{\"loop\":true,\"is_thumbnails\":false,\"has_thumbnails\":false,\"slidesPerView\":\"1\",\"slidesPerGroup\":1,\"autoHeight\":false,\"centeredSlides\":true,\"duplicatedItems\":true,\"itemsCount\":6,\"autoplay\":false,\"pagination\":{\"enabled\":true,\"clickable\":true,\"dynamicBullets\":false},\"navigation\":{\"enabled\":false},\"freeMode\":false,\"edgeTransitionParams\":{\"transitionZone\":1,\"slider_style\":\"pix-style-standard\",\"slider_effect\":\"pix-effect-standard\",\"slider_inactive_scale\":false,\"dragScale\":false},\"breakpoints\":{\"767\":{\"slidesPerView\":1},\"1024\":{\"slidesPerView\":1}}}'  data-slides-desktop=\"1\" data-slides-tablet=\"1\" data-slides-mobile=\"1\" ><div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-pixfort-slide-index=\"0\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-penthouse-1.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"1\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-penthouse-2.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"2\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-penthouse-4.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"3\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-penthouse-1.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"4\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-penthouse-2.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"5\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-penthouse-4.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pixfort-slider-pagination-container\"><div class=\"pixfort-slider-pagination\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-232ed1a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"232ed1a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b731d96\" data-id=\"b731d96\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fe6ffd elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8fe6ffd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e625c1\" data-id=\"4e625c1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9fc7e5 elementor-widget__width-inherit elementor-widget elementor-widget-pix-img-slider\" data-id=\"a9fc7e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-img-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pixfort-swiper position-relative   \"><div class=\"position-relative\"><div class=\"swiper  pix-style-standard pix-effect-standard \" data-swiper='{\"loop\":true,\"is_thumbnails\":false,\"has_thumbnails\":false,\"slidesPerView\":\"1\",\"slidesPerGroup\":1,\"autoHeight\":false,\"centeredSlides\":true,\"duplicatedItems\":false,\"itemsCount\":6,\"autoplay\":false,\"pagination\":{\"enabled\":true,\"clickable\":true,\"dynamicBullets\":false},\"navigation\":{\"enabled\":false},\"freeMode\":false,\"edgeTransitionParams\":{\"transitionZone\":1,\"slider_style\":\"pix-style-standard\",\"slider_effect\":\"pix-effect-standard\",\"slider_inactive_scale\":false,\"dragScale\":false},\"breakpoints\":{\"767\":{\"slidesPerView\":1},\"1024\":{\"slidesPerView\":1}}}'  data-slides-desktop=\"1\" data-slides-tablet=\"1\" data-slides-mobile=\"1\" ><div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-pixfort-slide-index=\"0\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-1.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"1\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-2.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"2\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-3.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"3\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-7.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"4\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-9.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"5\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-8.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pixfort-slider-pagination-container\"><div class=\"pixfort-slider-pagination\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-32546a6\" data-id=\"32546a6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-488833e elementor-widget elementor-widget-heading\" data-id=\"488833e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VILLA VENUS 3+1 \/ 4+1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-299998a elementor-widget elementor-widget-text-editor\" data-id=\"299998a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Get the ultimate in comfort in a duplex villa with direct access to the pool from the living room.  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a89edf9 animated-slow elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"a89edf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"katman_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 27.1 30.8\" style=\"enable-background:new 0 0 27.1 30.8;\" xml:space=\"preserve\"><path d=\"M7.3,14.9v-2.3h2.3v2.3H7.3z M17.3,14.9v-2.3h2.3v2.3H17.3z M0.2,30.5v-11h1.7v-7.4c0-1.6,0.3-3.1,0.9-4.5S4.2,5,5.3,3.9 C6.3,2.9,7.6,2,9,1.4c1.4-0.6,2.9-0.9,4.5-0.9s3.1,0.3,4.5,0.9c1.4,0.6,2.7,1.4,3.7,2.5c1.1,1.1,1.9,2.3,2.5,3.7s0.9,2.9,0.9,4.5 v7.4h1.7v11H0.2z M1.6,29.1h4.5V21H1.6V29.1z M7.5,29.1h5.3V21H7.5V29.1z M3.3,19.6h9.5V2c-2.5,0.1-4.7,1.1-6.6,3 c-1.9,1.9-2.9,4.3-2.9,7.2V19.6z M14.2,19.6h9.5v-7.4c0-2.9-1-5.3-2.9-7.2c-1.9-1.9-4.2-2.9-6.6-3V19.6z M14.2,29.1h5.3V21h-5.3 V29.1z M21,29.1h4.5V21H21V29.1z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBalcony\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32d4c36 animated-slow elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"32d4c36\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"katman_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 32.5 29.3\" style=\"enable-background:new 0 0 32.5 29.3;\" xml:space=\"preserve\"><path d=\"M0.4,28.7v-1.5c0.8-0.1,1.5-0.4,2.1-0.9c0.5-0.4,1.4-0.7,2.6-0.7S7.3,26,8,26.5c0.7,0.6,1.6,0.9,2.8,0.9s2-0.3,2.7-0.9 c0.7-0.6,1.6-0.9,2.8-0.9s2.2,0.3,2.9,0.9c0.7,0.6,1.6,0.9,2.8,0.9c1.2,0,2.1-0.3,2.7-0.9c0.6-0.6,1.6-0.9,2.8-0.9 c1.2,0,2.1,0.2,2.6,0.7c0.5,0.4,1.2,0.7,2.1,0.9v1.5c-0.8-0.1-1.5-0.4-2.1-0.9c-0.6-0.5-1.5-0.7-2.6-0.7c-1.1,0-1.9,0.3-2.6,0.9 c-0.7,0.6-1.6,0.9-2.9,0.9c-1.2,0-2.2-0.3-3-0.9c-0.7-0.6-1.6-0.9-2.7-0.9s-1.9,0.3-2.6,0.9c-0.7,0.6-1.7,0.9-2.9,0.9 c-1.3,0-2.3-0.3-3-0.9c-0.7-0.6-1.6-0.9-2.6-0.9s-1.9,0.2-2.5,0.7C1.9,28.3,1.2,28.6,0.4,28.7z M0.4,21.1v-1.5 c0.8-0.1,1.5-0.4,2.1-0.9c0.5-0.4,1.4-0.7,2.6-0.7S7.3,18.4,8,19c0.7,0.6,1.6,0.8,2.8,0.8c1.1,0,2-0.3,2.7-0.8 c0.7-0.6,1.6-0.8,2.8-0.8s2.2,0.3,2.8,0.8c0.7,0.6,1.6,0.8,2.8,0.8c1.1,0,2-0.3,2.7-0.8c0.7-0.6,1.6-0.8,2.8-0.8 c1.2,0,2.1,0.2,2.6,0.7c0.5,0.4,1.2,0.7,2.1,0.9v1.5c-0.8-0.1-1.5-0.4-2.1-0.9c-0.6-0.5-1.5-0.7-2.6-0.7c-1.1,0-1.9,0.3-2.6,0.9 c-0.7,0.6-1.6,0.9-2.9,0.9c-1.2,0-2.2-0.3-3-0.9c-0.7-0.6-1.6-0.9-2.7-0.9s-1.9,0.3-2.6,0.9c-0.7,0.6-1.6,0.9-2.9,0.9 c-1.3,0-2.3-0.3-3-0.9c-0.7-0.6-1.6-0.9-2.6-0.9s-1.9,0.2-2.5,0.7C1.9,20.7,1.2,21,0.4,21.1z M9.4,13.1l5.4-5.4L12,5 c-0.9-0.9-1.8-1.5-2.7-1.9S7.3,2.6,5.9,2.5v-2C7.6,0.5,9,0.8,10.1,1.2c1.1,0.4,2.2,1.2,3.4,2.4l9.7,9.7c-0.1,0.1-0.3,0.3-0.6,0.3 c-0.2,0.1-0.5,0.1-0.7,0.1c-0.8,0-1.5-0.3-2.3-0.9c-0.8-0.6-1.9-0.9-3.3-0.9s-2.5,0.3-3.3,0.9c-0.8,0.6-1.5,0.9-2.3,0.9 c-0.3,0-0.5-0.1-0.8-0.2C9.7,13.4,9.5,13.3,9.4,13.1z M23.6,0.9c1,0,1.8,0.3,2.5,1c0.7,0.7,1,1.5,1,2.4c0,1-0.3,1.8-1,2.5 c-0.7,0.7-1.5,1-2.5,1s-1.8-0.3-2.5-1s-1-1.5-1-2.5c0-0.9,0.3-1.8,1-2.4S22.7,0.9,23.6,0.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBalcony\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b5577e5 animated-slow elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"b5577e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"katman_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 39.6 38.9\" style=\"enable-background:new 0 0 39.6 38.9;\" xml:space=\"preserve\"><path d=\"M19.7,38.3c-2.7,0-5.2-0.5-7.5-1.5s-4.3-2.3-6.1-4c-1.7-1.7-3.1-3.7-4-6s-1.4-4.8-1.4-7.5c0-2.6,0.5-5.1,1.4-7.4 s2.3-4.3,4-6.1s3.7-3.1,6.1-4.1c2.3-1,4.8-1.5,7.5-1.5c2.4,0,4.6,0.4,6.6,1.1s3.9,1.8,5.6,3.1l-1.6,1.6c-1.5-1.2-3.1-2.1-4.9-2.7 s-3.7-0.9-5.7-0.9C15,2.5,11,4.1,7.8,7.3s-4.8,7.2-4.8,11.9S4.5,28,7.8,31.2S15,36,19.7,36s8.7-1.6,11.9-4.8s4.8-7.2,4.8-11.9 c0-1-0.1-2-0.2-2.9c-0.2-0.9-0.4-1.8-0.7-2.7l1.8-1.8c0.5,1.1,0.8,2.3,1.1,3.5s0.4,2.5,0.4,3.8c0,2.7-0.5,5.2-1.5,7.5 s-2.3,4.3-4,6.1c-1.7,1.7-3.7,3.1-6,4S22.4,38.3,19.7,38.3z M16.7,27.7l-7.6-7.6l1.7-1.8l5.9,5.9L37,4l1.8,1.7L16.7,27.7z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tShower and Bathtub\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-793171b elementor-widget__width-auto elementor-widget elementor-widget-pix-button\" data-id=\"793171b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  href=\"https:\/\/sianjilife.com\/wp-content\/uploads\/2023\/03\/PHOTO-2023-03-23-15-44-57-2.jpg\" class=\"btn m-0      btn-brown d-inline-flex align-items-center      btn-sm\" target=\"_blank\" rel=\"noopener\"    ><span class=\"font-weight-bold \" >360 Tour<\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a854098 elementor-widget__width-auto elementor-widget elementor-widget-pix-button\" data-id=\"a854098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  href=\"https:\/\/l24.im\/8wC\" class=\"btn m-0      btn-brown d-inline-flex align-items-center      btn-sm\" target=\"_blank\" rel=\"noopener\"    ><span class=\"font-weight-bold \" >Room Video<\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3fda8c elementor-widget__width-auto elementor-widget elementor-widget-pix-button\" data-id=\"b3fda8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  href=\"https:\/\/l24.im\/nA8m\" class=\"btn m-0      btn-brown d-inline-flex align-items-center      btn-sm\" target=\"_blank\" rel=\"noopener\"    ><span class=\"font-weight-bold \" >360 Tour<\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-469a314 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"469a314\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ae1188\" data-id=\"8ae1188\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82c04e1 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"82c04e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f064f84\" data-id=\"f064f84\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a5d36f elementor-widget elementor-widget-heading\" data-id=\"0a5d36f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VENUS VILLA 2+1<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5258c95 elementor-widget elementor-widget-text-editor\" data-id=\"5258c95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Get the ultimate in comfort in a duplex villa with direct access to the pool from the living room.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6142e47 animated-slow elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"6142e47\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"katman_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 27.1 30.8\" style=\"enable-background:new 0 0 27.1 30.8;\" xml:space=\"preserve\"><path d=\"M7.3,14.9v-2.3h2.3v2.3H7.3z M17.3,14.9v-2.3h2.3v2.3H17.3z M0.2,30.5v-11h1.7v-7.4c0-1.6,0.3-3.1,0.9-4.5S4.2,5,5.3,3.9 C6.3,2.9,7.6,2,9,1.4c1.4-0.6,2.9-0.9,4.5-0.9s3.1,0.3,4.5,0.9c1.4,0.6,2.7,1.4,3.7,2.5c1.1,1.1,1.9,2.3,2.5,3.7s0.9,2.9,0.9,4.5 v7.4h1.7v11H0.2z M1.6,29.1h4.5V21H1.6V29.1z M7.5,29.1h5.3V21H7.5V29.1z M3.3,19.6h9.5V2c-2.5,0.1-4.7,1.1-6.6,3 c-1.9,1.9-2.9,4.3-2.9,7.2V19.6z M14.2,19.6h9.5v-7.4c0-2.9-1-5.3-2.9-7.2c-1.9-1.9-4.2-2.9-6.6-3V19.6z M14.2,29.1h5.3V21h-5.3 V29.1z M21,29.1h4.5V21H21V29.1z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBalcony\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56f848c animated-slow elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"56f848c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"katman_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 32.5 29.3\" style=\"enable-background:new 0 0 32.5 29.3;\" xml:space=\"preserve\"><path d=\"M0.4,28.7v-1.5c0.8-0.1,1.5-0.4,2.1-0.9c0.5-0.4,1.4-0.7,2.6-0.7S7.3,26,8,26.5c0.7,0.6,1.6,0.9,2.8,0.9s2-0.3,2.7-0.9 c0.7-0.6,1.6-0.9,2.8-0.9s2.2,0.3,2.9,0.9c0.7,0.6,1.6,0.9,2.8,0.9c1.2,0,2.1-0.3,2.7-0.9c0.6-0.6,1.6-0.9,2.8-0.9 c1.2,0,2.1,0.2,2.6,0.7c0.5,0.4,1.2,0.7,2.1,0.9v1.5c-0.8-0.1-1.5-0.4-2.1-0.9c-0.6-0.5-1.5-0.7-2.6-0.7c-1.1,0-1.9,0.3-2.6,0.9 c-0.7,0.6-1.6,0.9-2.9,0.9c-1.2,0-2.2-0.3-3-0.9c-0.7-0.6-1.6-0.9-2.7-0.9s-1.9,0.3-2.6,0.9c-0.7,0.6-1.7,0.9-2.9,0.9 c-1.3,0-2.3-0.3-3-0.9c-0.7-0.6-1.6-0.9-2.6-0.9s-1.9,0.2-2.5,0.7C1.9,28.3,1.2,28.6,0.4,28.7z M0.4,21.1v-1.5 c0.8-0.1,1.5-0.4,2.1-0.9c0.5-0.4,1.4-0.7,2.6-0.7S7.3,18.4,8,19c0.7,0.6,1.6,0.8,2.8,0.8c1.1,0,2-0.3,2.7-0.8 c0.7-0.6,1.6-0.8,2.8-0.8s2.2,0.3,2.8,0.8c0.7,0.6,1.6,0.8,2.8,0.8c1.1,0,2-0.3,2.7-0.8c0.7-0.6,1.6-0.8,2.8-0.8 c1.2,0,2.1,0.2,2.6,0.7c0.5,0.4,1.2,0.7,2.1,0.9v1.5c-0.8-0.1-1.5-0.4-2.1-0.9c-0.6-0.5-1.5-0.7-2.6-0.7c-1.1,0-1.9,0.3-2.6,0.9 c-0.7,0.6-1.6,0.9-2.9,0.9c-1.2,0-2.2-0.3-3-0.9c-0.7-0.6-1.6-0.9-2.7-0.9s-1.9,0.3-2.6,0.9c-0.7,0.6-1.6,0.9-2.9,0.9 c-1.3,0-2.3-0.3-3-0.9c-0.7-0.6-1.6-0.9-2.6-0.9s-1.9,0.2-2.5,0.7C1.9,20.7,1.2,21,0.4,21.1z M9.4,13.1l5.4-5.4L12,5 c-0.9-0.9-1.8-1.5-2.7-1.9S7.3,2.6,5.9,2.5v-2C7.6,0.5,9,0.8,10.1,1.2c1.1,0.4,2.2,1.2,3.4,2.4l9.7,9.7c-0.1,0.1-0.3,0.3-0.6,0.3 c-0.2,0.1-0.5,0.1-0.7,0.1c-0.8,0-1.5-0.3-2.3-0.9c-0.8-0.6-1.9-0.9-3.3-0.9s-2.5,0.3-3.3,0.9c-0.8,0.6-1.5,0.9-2.3,0.9 c-0.3,0-0.5-0.1-0.8-0.2C9.7,13.4,9.5,13.3,9.4,13.1z M23.6,0.9c1,0,1.8,0.3,2.5,1c0.7,0.7,1,1.5,1,2.4c0,1-0.3,1.8-1,2.5 c-0.7,0.7-1.5,1-2.5,1s-1.8-0.3-2.5-1s-1-1.5-1-2.5c0-0.9,0.3-1.8,1-2.4S22.7,0.9,23.6,0.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tBalcony\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eab7a9b animated-slow elementor-position-inline-start elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"eab7a9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"katman_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 39.6 38.9\" style=\"enable-background:new 0 0 39.6 38.9;\" xml:space=\"preserve\"><path d=\"M19.7,38.3c-2.7,0-5.2-0.5-7.5-1.5s-4.3-2.3-6.1-4c-1.7-1.7-3.1-3.7-4-6s-1.4-4.8-1.4-7.5c0-2.6,0.5-5.1,1.4-7.4 s2.3-4.3,4-6.1s3.7-3.1,6.1-4.1c2.3-1,4.8-1.5,7.5-1.5c2.4,0,4.6,0.4,6.6,1.1s3.9,1.8,5.6,3.1l-1.6,1.6c-1.5-1.2-3.1-2.1-4.9-2.7 s-3.7-0.9-5.7-0.9C15,2.5,11,4.1,7.8,7.3s-4.8,7.2-4.8,11.9S4.5,28,7.8,31.2S15,36,19.7,36s8.7-1.6,11.9-4.8s4.8-7.2,4.8-11.9 c0-1-0.1-2-0.2-2.9c-0.2-0.9-0.4-1.8-0.7-2.7l1.8-1.8c0.5,1.1,0.8,2.3,1.1,3.5s0.4,2.5,0.4,3.8c0,2.7-0.5,5.2-1.5,7.5 s-2.3,4.3-4,6.1c-1.7,1.7-3.7,3.1-6,4S22.4,38.3,19.7,38.3z M16.7,27.7l-7.6-7.6l1.7-1.8l5.9,5.9L37,4l1.8,1.7L16.7,27.7z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tShower and Bathtub\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9f1fa9 elementor-widget__width-auto elementor-widget elementor-widget-pix-button\" data-id=\"f9f1fa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  href=\"https:\/\/sianjilife.com\/wp-content\/uploads\/2023\/03\/Venus-Villa21-Kat-Plani.pdf\" class=\"btn m-0      btn-brown d-inline-flex align-items-center      btn-sm\" target=\"_blank\" rel=\"noopener\"    ><span class=\"font-weight-bold \" >360 Tour<\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e6247f elementor-widget__width-auto elementor-widget elementor-widget-pix-button\" data-id=\"5e6247f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  href=\"https:\/\/l24.im\/8wC\" class=\"btn m-0      btn-brown d-inline-flex align-items-center      btn-sm\" target=\"_blank\" rel=\"noopener\"    ><span class=\"font-weight-bold \" >Room Video<\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ba5ec7 elementor-widget__width-auto elementor-widget elementor-widget-pix-button\" data-id=\"9ba5ec7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a  href=\"https:\/\/l24.im\/UzJ\" class=\"btn m-0      btn-brown d-inline-flex align-items-center      btn-sm\" target=\"_blank\" rel=\"noopener\"    ><span class=\"font-weight-bold \" >360 Tour<\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bfb8b8f\" data-id=\"bfb8b8f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd5649b elementor-widget__width-inherit elementor-widget elementor-widget-pix-img-slider\" data-id=\"fd5649b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-img-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pixfort-swiper position-relative   \"><div class=\"position-relative\"><div class=\"swiper  pix-style-standard pix-effect-standard \" data-swiper='{\"loop\":true,\"is_thumbnails\":false,\"has_thumbnails\":false,\"slidesPerView\":\"1\",\"slidesPerGroup\":1,\"autoHeight\":false,\"centeredSlides\":true,\"duplicatedItems\":false,\"itemsCount\":5,\"autoplay\":false,\"pagination\":{\"enabled\":true,\"clickable\":true,\"dynamicBullets\":false},\"navigation\":{\"enabled\":false},\"freeMode\":false,\"edgeTransitionParams\":{\"transitionZone\":1,\"slider_style\":\"pix-style-standard\",\"slider_effect\":\"pix-effect-standard\",\"slider_inactive_scale\":false,\"dragScale\":false},\"breakpoints\":{\"767\":{\"slidesPerView\":1},\"1024\":{\"slidesPerView\":1}}}'  data-slides-desktop=\"1\" data-slides-tablet=\"1\" data-slides-mobile=\"1\" ><div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-pixfort-slide-index=\"0\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-6.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"1\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-3.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"2\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-7.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"3\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-9.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\" data-pixfort-slide-index=\"4\"><div class=\"pixfort-slide-inner  pix-p-10\"><div class=\"None \"><div class=\"\"><div class=\"  text-left w-100 d-inline-block rounded-0\"  ><img loading=\"lazy\" decoding=\"async\" loading=\"lazy\" class=\"card-img rounded-0 h-100\" src=\"https:\/\/i0.wp.com\/sianjilife.com\/wp-content\/uploads\/2023\/03\/sianji-villa-swim-up-8.jpg?fit=1300%2C700&#038;ssl=1\" alt=\"\" width=\"1300\" height=\"700\" style=\"\"\/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"pixfort-slider-pagination-container\"><div class=\"pixfort-slider-pagination\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5e8cc44 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"5e8cc44\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c546a6c\" data-id=\"c546a6c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6eda83c7 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6eda83c7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-435f19c8\" data-id=\"435f19c8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-74ddb5ca elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"74ddb5ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4f9591ff\" data-id=\"4f9591ff\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32aab5c8 elementor-widget elementor-widget-text-editor\" data-id=\"32aab5c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"privacy-title mt-4 mb-4\">TECHNICAL SPECIFICATION<\/h3>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3f16bd elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b3f16bd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6fc47037\" data-id=\"6fc47037\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ab8ac4c privacy elementor-widget elementor-widget-pix-accordion\" data-id=\"5ab8ac4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"accordion w-100 accordion-card\" id=\"accordion-5ab8ac4c\"><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-259ff90\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-259ff90\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-259ff90\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >STRUCTURE FEATURES<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-259ff90\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-259ff90\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">All of the buildings were constructed as two-storey reinforced concrete frame or steel construction.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Calculations were made in accordance with the latest earthquake regulations and BS:25 was used in the carcass, foundation columns, beams and slabs. In reinforced concrete, ribbed iron was used and stirrups were tightened in beam and column bearings.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-0035181\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-0035181\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-0035181\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >EXTERIOR WALL FEATURES<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-0035181\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-0035181\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Column spaces were built with hollow bricks, walls, columns and beams were sheathed from the outside with 3cm extruded polystyrene sheets in accordance with the project and technique. Bituminous material was used for waterproofing on the ground and roofs. Special plaster and acrylic paint were applied outside the sheathing and the blocks shown in the project were covered with yellow slate.Balconies are made of reinforced concrete or impregnated wood according to the project.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">The terraces resting on the ground are covered with non-slip ceramic or flooring material (8 Terra level) over grout concrete. Exterior and interior walls are made of insulated aerated concrete (ytong).<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-8369ed0\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-8369ed0\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-8369ed0\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >EXTERIOR JOINERY FEATURES<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-8369ed0\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-8369ed0\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Small sized windows are made with Decolink brand TSE quality PVC profiles with heat glazing, while lobby, halls, restaurants and similar windows larger than 3 m2 are made of insulated aluminum joinery.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-5a61c56\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-5a61c56\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-5a61c56\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >FLOOR MATERIALS<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-5a61c56\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-5a61c56\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Imported ceramic tiles were used in the entrance areas, imported laminated parquet was used in the living room and living spaces, and imported carpets were used in the rooms. Bathroom+wc floors are made of Aparici brand imported ceramic, terraces and balconies are made of ceramic stairs, stairs and risers are made of laminated parquet, handrails are anodized or perforated.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-ae75f57\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-ae75f57\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-ae75f57\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >WALL COVERING MATERIALS<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-ae75f57\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-ae75f57\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">1 on the walls. quality satin paint and imported wallpaper, Aparici brand imported ceramic tiles were used in bathrooms and wc's.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-3af9d75\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-3af9d75\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-3af9d75\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >CEILING MATERIALS<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-3af9d75\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-3af9d75\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Drywall and plasterboard were used according to the space and decoration.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-24bd448\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-24bd448\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-24bd448\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >FURNITURE AND FIXED WOOD PRODUCTS<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-24bd448\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-24bd448\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">All furniture is specially manufactured according to the project. Imported veneer, MDF, solid wood and imported accessories are used in manufacturing (door handle, handle, hinge, etc.)<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-b5962ab\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-b5962ab\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-b5962ab\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >VITRIFIED<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-b5962ab\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-b5962ab\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">In sanitary ware materials, bathtubs, shower trays and cabins are made of Huppe brand and Duravit brand imported products are used in toilet bowls and washbasins. Grohe brand imported materials are used in all bathroom and kitchen fixtures.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-22e948c\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-22e948c\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-22e948c\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >BATHROOM AND KITCHEN COUNTERTOPS<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-22e948c\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-22e948c\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Bathroom and kitchen countertops are Grapol brand acrylic material.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-4705579\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-4705579\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-4705579\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >KITCHEN<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-4705579\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-4705579\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Siemens products were used in white goods (Countertop, Refrigerator, Built-in Cooker, Oven, Sink, Sink armature, Aspirator, Dishwasher, washing machine, , Minibar,).<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-0460e07\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-0460e07\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-0460e07\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >AIR CONDITIONING SYSTEM<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-0460e07\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-0460e07\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">LG brand was used. The system is used as split or VRF. (There is a heating and cooling unit.)<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-888f5cf\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-888f5cf\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-888f5cf\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >TELEVISION, INTERNET AND TELEPHONE<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-888f5cf\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-888f5cf\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">SAMSUNG brand 32 inch LCD TVs are used in the living area of all residences and 22 inch LCD TVs are used in the master bedrooms. Wireless internet is available in all rooms. Each room has a telephone line connected to the switchboard.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-00d948b\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-00d948b\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-00d948b\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >LIGHTING<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-00d948b\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-00d948b\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Indirect lighting is custom made depending on the design. Materials such as switches, sockets, spotlights are selected from 1st quality TSE products.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-af22dae\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-af22dae\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-af22dae\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >TEXTILE<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-af22dae\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-af22dae\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Cover, curtain, tulle, roller blind and bedding sets made of quality fabrics are used. In addition, there are as many towels, bathrobes and beach towels in each room as the number of beds.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-70d2bbb\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-70d2bbb\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-70d2bbb\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >ACCESSORY<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-70d2bbb\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-70d2bbb\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Depending on the design, there are original or classic paintings, sculptures, murals and accessories.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-5ab8ac4c-f4307c5\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-5ab8ac4c-f4307c5\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-5ab8ac4c-f4307c5\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >FIREPLACE<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-5ab8ac4c-f4307c5\" class=\"collapse \" aria-labelledby=\"headingpix-tab-5ab8ac4c-f4307c5\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">The fireplaces in Semiramis and Venus Residences vary in style or material according to the period and Drayton Effect brand and model imported fireplaces are used.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-117d701 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"117d701\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0bb82e9\" data-id=\"0bb82e9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e23d7df elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"e23d7df\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-28e4258\" data-id=\"28e4258\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad3390c elementor-widget elementor-widget-text-editor\" data-id=\"ad3390c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"privacy-title mt-4 mb-4\">FEE DETAILS<\/h3>\n<p><span style=\"font-weight: 500;\">The services that the owners of Sianji Villa &amp; Residence will receive in return for the dues they will pay are explained in detail below;<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec017d0 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"ec017d0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca9816b\" data-id=\"ca9816b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89921f5 privacy elementor-widget elementor-widget-pix-accordion\" data-id=\"89921f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"accordion w-100 accordion-card\" id=\"accordion-89921f5\"><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-89921f5-259ff90\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-89921f5-259ff90\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-89921f5-259ff90\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >Security Services<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-89921f5-259ff90\" class=\"collapse \" aria-labelledby=\"headingpix-tab-89921f5-259ff90\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">24-hour security guards at all entrances, exits and parking lots of the residences, as well as a camera security system at strategic points.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-89921f5-0035181\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-89921f5-0035181\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-89921f5-0035181\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >Welcome and Communication Services (Concierge) ;<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-89921f5-0035181\" class=\"collapse \" aria-labelledby=\"headingpix-tab-89921f5-0035181\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Reception, guest relations, valet parking, bellboy, switchboard needs of all residence guests are met by the staff.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-89921f5-8369ed0\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-89921f5-8369ed0\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-89921f5-8369ed0\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >Housekeeping Services<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-89921f5-8369ed0\" class=\"collapse \" aria-labelledby=\"headingpix-tab-89921f5-8369ed0\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">When residents use the residences, housekeeping service will be provided 2 days a week, and when they do not use the residences, ventilation and control service will be provided every day. In addition, cleaning of all residence common areas (parking lot, corridors, walkways, etc.) is included in the fee.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-89921f5-5a61c56\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-89921f5-5a61c56\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-89921f5-5a61c56\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >Laundry Services<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-89921f5-5a61c56\" class=\"collapse \" aria-labelledby=\"headingpix-tab-89921f5-5a61c56\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">During the housekeeping service, towels, bed linen, sheets and pillowcases will be replaced with clean ones 2 days a week.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-89921f5-ae75f57\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-89921f5-ae75f57\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-89921f5-ae75f57\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >Park, Garden and Landscape Services<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-89921f5-ae75f57\" class=\"collapse \" aria-labelledby=\"headingpix-tab-89921f5-ae75f57\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">The garden of the residence owners and the park, garden and landscaping of all common areas (planting, planting, watering, pruning, spraying, etc.) will be organized by the gardener team.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-89921f5-3af9d75\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-89921f5-3af9d75\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-89921f5-3af9d75\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >Wireless Internet<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-89921f5-3af9d75\" class=\"collapse \" aria-labelledby=\"headingpix-tab-89921f5-3af9d75\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">High speed internet access in all indoor and outdoor areas and inside the residence.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-89921f5-24bd448\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-89921f5-24bd448\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-89921f5-24bd448\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >Beach Club and Pool Maintenance Services<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-89921f5-24bd448\" class=\"collapse \" aria-labelledby=\"headingpix-tab-89921f5-24bd448\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">All beach club use and maintenance, maintenance of pools (filtration and disinfection).<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-89921f5-b5962ab\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-89921f5-b5962ab\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-89921f5-b5962ab\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >Use of Fitness Center, Turkish Bath, Sauna, Steam Bath and Pools;<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-89921f5-b5962ab\" class=\"collapse \" aria-labelledby=\"headingpix-tab-89921f5-b5962ab\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">Fitness center activities accompanied by sports trainers and the use of Turkish Bath, Sauna, Steam Bath, Outdoor Pool, Indoor Pool, Thalasso Pool are included in the service.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><div class=\"card\">\n               <div class=\"card-header shadow-sm rounded-lg bg-custom\" id=\"headingpix-tab-89921f5-22e948c\" style=\"background:#EEF2F1 !important\">\n                   <button class=\"btn btn-link d-flex text-left\" type=\"button\" data-toggle=\"collapse\" data-target=\"#collapsepix-tab-89921f5-22e948c\" aria-expanded=\"true\" aria-controls=\"collapsepix-tab-89921f5-22e948c\"><span class=\"d-inline-flex align-self-center text-primary svg-202 text-20 pix-mr-10\"><i class=\" \"><\/i><\/span><span class=\"d-inline-flex font-weight-bold text-black\" >Use and Maintenance of Sports Fields<\/span><\/button>\n               <\/div>\n\n               <div id=\"collapsepix-tab-89921f5-22e948c\" class=\"collapse \" aria-labelledby=\"headingpix-tab-89921f5-22e948c\">\n                 <div class=\"card-body\"><p><span style=\"font-weight: 400;\">You can engage in various sport activities, such as basketball, volleyball and tennis courts. The maintenance and repair of these sports facilities are covered by common expenses.<\/span><\/p>\n<\/div>\n               <\/div>\n             <\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-147413d4 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"147413d4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c9449f4\" data-id=\"4c9449f4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-41c44487 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"41c44487\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-51e10b5a\" data-id=\"51e10b5a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31b18655 elementor-widget elementor-widget-spacer\" data-id=\"31b18655\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-309918db elementor-widget elementor-widget-heading\" data-id=\"309918db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get in touch with us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3573f0f fontchange elementor-widget elementor-widget-pix-feature\" data-id=\"3573f0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pix-feature.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pix-feature-3573f0f\" class=\"pix-feature-el text-custom \"><div class=\"pix-feature-title  font-weight-bold   text-heading-default \" style=\"font-size:;\"  >Address<\/div><div class=\"pix-feature-content text-body-default text-sm     \" style=\"padding-top:10px;\"  >Peksimet Mahallesi Kadikalesi Mevkii 48400 Gumusluk, Bodrum - Mugla \/ Turkey<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35b5e752 elementor-widget elementor-widget-heading\" data-id=\"35b5e752\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Contact<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4195f83 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4195f83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:423424234\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+90 533 550 56 59<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@sianji.com<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/wa.me\/message\/URORK4QRQPPFO1\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Whatsapp<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c45e458 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"6c45e458\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c5b77a8\" data-id=\"3c5b77a8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;pix_scale_in&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"A privileged life embracing the deep blue sea of Bodrum! While the world is changing rapidly, we offer you a life where you feel peaceful with the future assurance of the value your investment gains, with the relaxing and refreshing","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","nf_dc_page":"","googlesitekit_rrm_CAow6IK3DA:productID":"","footnotes":""},"class_list":["post-17381","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sianji Villa &amp; Residence - SIANJI Well-Being Resort<\/title>\n<meta name=\"description\" content=\"Own a home in Bodrum with a spectacular view, in seafront villas and residences with the comfort of a 5-star hotel!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sianji Villa &amp; Residence - SIANJI Well-Being Resort\" \/>\n<meta property=\"og:description\" content=\"Own a home in Bodrum with a spectacular view, in seafront villas and residences with the comfort of a 5-star hotel!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/\" \/>\n<meta property=\"og:site_name\" content=\"SIANJI Well-Being Resort\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/sianjibodrum\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-24T23:55:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sianjilife.com\/wp-content\/uploads\/2023\/03\/Sianji-Villa-Residence-Logo-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@sianjibodrum\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/sianji-villa-residence\\\/\",\"url\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/sianji-villa-residence\\\/\",\"name\":\"Sianji Villa &amp; Residence - SIANJI Well-Being Resort\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/sianji-villa-residence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/sianji-villa-residence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sianjilife.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Sianji-Villa-Residence-Logo-1.png\",\"datePublished\":\"2023-03-22T13:57:50+00:00\",\"dateModified\":\"2023-03-24T23:55:39+00:00\",\"description\":\"Own a home in Bodrum with a spectacular view, in seafront villas and residences with the comfort of a 5-star hotel!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/sianji-villa-residence\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sianjilife.com\\\/en\\\/sianji-villa-residence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/sianji-villa-residence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sianjilife.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Sianji-Villa-Residence-Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/sianjilife.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Sianji-Villa-Residence-Logo-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/sianji-villa-residence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sianji Villa &amp; Residence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/\",\"name\":\"Sianji Well Being Resort\",\"description\":\"Holistic healing and a pleasant vacation!\",\"publisher\":{\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/#organization\",\"name\":\"Sianji Well Being Resort\",\"url\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sianjilife.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/sianji-black-logo-new.svg\",\"contentUrl\":\"https:\\\/\\\/sianjilife.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/sianji-black-logo-new.svg\",\"width\":803,\"height\":212,\"caption\":\"Sianji Well Being Resort\"},\"image\":{\"@id\":\"https:\\\/\\\/sianjilife.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/sianjibodrum\",\"https:\\\/\\\/x.com\\\/sianjibodrum\",\"https:\\\/\\\/instagram.com\\\/sianji\",\"https:\\\/\\\/www.tripadvisor.com.tr\\\/UserReviewEdit-d1553772\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sianji Villa &amp; Residence - SIANJI Well-Being Resort","description":"Own a home in Bodrum with a spectacular view, in seafront villas and residences with the comfort of a 5-star hotel!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/","og_locale":"en_US","og_type":"article","og_title":"Sianji Villa &amp; Residence - SIANJI Well-Being Resort","og_description":"Own a home in Bodrum with a spectacular view, in seafront villas and residences with the comfort of a 5-star hotel!","og_url":"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/","og_site_name":"SIANJI Well-Being Resort","article_publisher":"http:\/\/facebook.com\/sianjibodrum","article_modified_time":"2023-03-24T23:55:39+00:00","og_image":[{"url":"https:\/\/sianjilife.com\/wp-content\/uploads\/2023\/03\/Sianji-Villa-Residence-Logo-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@sianjibodrum","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/","url":"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/","name":"Sianji Villa &amp; Residence - SIANJI Well-Being Resort","isPartOf":{"@id":"https:\/\/sianjilife.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/#primaryimage"},"image":{"@id":"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/#primaryimage"},"thumbnailUrl":"https:\/\/sianjilife.com\/wp-content\/uploads\/2023\/03\/Sianji-Villa-Residence-Logo-1.png","datePublished":"2023-03-22T13:57:50+00:00","dateModified":"2023-03-24T23:55:39+00:00","description":"Own a home in Bodrum with a spectacular view, in seafront villas and residences with the comfort of a 5-star hotel!","breadcrumb":{"@id":"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sianjilife.com\/en\/sianji-villa-residence\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/#primaryimage","url":"https:\/\/sianjilife.com\/wp-content\/uploads\/2023\/03\/Sianji-Villa-Residence-Logo-1.png","contentUrl":"https:\/\/sianjilife.com\/wp-content\/uploads\/2023\/03\/Sianji-Villa-Residence-Logo-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/sianjilife.com\/en\/sianji-villa-residence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sianjilife.com\/en\/"},{"@type":"ListItem","position":2,"name":"Sianji Villa &amp; Residence"}]},{"@type":"WebSite","@id":"https:\/\/sianjilife.com\/en\/#website","url":"https:\/\/sianjilife.com\/en\/","name":"Sianji Well Being Resort","description":"Holistic healing and a pleasant vacation!","publisher":{"@id":"https:\/\/sianjilife.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sianjilife.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sianjilife.com\/en\/#organization","name":"Sianji Well Being Resort","url":"https:\/\/sianjilife.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sianjilife.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sianjilife.com\/wp-content\/uploads\/2023\/01\/sianji-black-logo-new.svg","contentUrl":"https:\/\/sianjilife.com\/wp-content\/uploads\/2023\/01\/sianji-black-logo-new.svg","width":803,"height":212,"caption":"Sianji Well Being Resort"},"image":{"@id":"https:\/\/sianjilife.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/sianjibodrum","https:\/\/x.com\/sianjibodrum","https:\/\/instagram.com\/sianji","https:\/\/www.tripadvisor.com.tr\/UserReviewEdit-d1553772"]}]}},"_links":{"self":[{"href":"https:\/\/sianjilife.com\/en\/wp-json\/wp\/v2\/pages\/17381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sianjilife.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sianjilife.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sianjilife.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/sianjilife.com\/en\/wp-json\/wp\/v2\/comments?post=17381"}],"version-history":[{"count":0,"href":"https:\/\/sianjilife.com\/en\/wp-json\/wp\/v2\/pages\/17381\/revisions"}],"wp:attachment":[{"href":"https:\/\/sianjilife.com\/en\/wp-json\/wp\/v2\/media?parent=17381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}